{"id":370,"date":"2024-09-03T08:42:53","date_gmt":"2024-09-03T06:42:53","guid":{"rendered":"http:\/\/projekt.zumloewen.com.dd48310.kasserver.com\/zimmer\/ferienwohnung\/"},"modified":"2024-09-11T13:53:52","modified_gmt":"2024-09-11T11:53:52","slug":"appartamento-per-le-vacanze","status":"publish","type":"zimmer","link":"https:\/\/www.zumloewen.com\/it\/camere\/appartamento-per-le-vacanze\/","title":{"rendered":"Appartamento per le vacanze"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"class_list":["post-370","zimmer","type-zimmer","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Appartamento per le vacanze a Meltina | Hotel zum L\u00f6wen<\/title>\n<meta name=\"description\" content=\"Il nostro accogliente appartamento per le vacanze vi offre la sistemazione perfetta per una vacanza indipendente a Meltina.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zumloewen.com\/it\/camere\/appartamento-per-le-vacanze\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Appartamento per le vacanze a Meltina | Hotel zum L\u00f6wen\" \/>\n<meta property=\"og:description\" content=\"Il nostro accogliente appartamento per le vacanze vi offre la sistemazione perfetta per una vacanza indipendente a Meltina.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zumloewen.com\/it\/camere\/appartamento-per-le-vacanze\/\" \/>\n<meta property=\"og:site_name\" content=\"Zum L\u00f6wen M\u00f6lten\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-11T11:53:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zumloewen.com\\\/it\\\/camere\\\/appartamento-per-le-vacanze\\\/\",\"url\":\"https:\\\/\\\/www.zumloewen.com\\\/it\\\/camere\\\/appartamento-per-le-vacanze\\\/\",\"name\":\"Appartamento per le vacanze a Meltina | Hotel zum L\u00f6wen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zumloewen.com\\\/it\\\/#website\"},\"datePublished\":\"2024-09-03T06:42:53+00:00\",\"dateModified\":\"2024-09-11T11:53:52+00:00\",\"description\":\"Il nostro accogliente appartamento per le vacanze vi offre la sistemazione perfetta per una vacanza indipendente a Meltina.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zumloewen.com\\\/it\\\/camere\\\/appartamento-per-le-vacanze\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zumloewen.com\\\/it\\\/camere\\\/appartamento-per-le-vacanze\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zumloewen.com\\\/it\\\/camere\\\/appartamento-per-le-vacanze\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.zumloewen.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Appartamento per le vacanze\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zumloewen.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.zumloewen.com\\\/it\\\/\",\"name\":\"Zum L\u00f6wen M\u00f6lten\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zumloewen.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Appartamento per le vacanze a Meltina | Hotel zum L\u00f6wen","description":"Il nostro accogliente appartamento per le vacanze vi offre la sistemazione perfetta per una vacanza indipendente a Meltina.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zumloewen.com\/it\/camere\/appartamento-per-le-vacanze\/","og_locale":"it_IT","og_type":"article","og_title":"Appartamento per le vacanze a Meltina | Hotel zum L\u00f6wen","og_description":"Il nostro accogliente appartamento per le vacanze vi offre la sistemazione perfetta per una vacanza indipendente a Meltina.","og_url":"https:\/\/www.zumloewen.com\/it\/camere\/appartamento-per-le-vacanze\/","og_site_name":"Zum L\u00f6wen M\u00f6lten","article_modified_time":"2024-09-11T11:53:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.zumloewen.com\/it\/camere\/appartamento-per-le-vacanze\/","url":"https:\/\/www.zumloewen.com\/it\/camere\/appartamento-per-le-vacanze\/","name":"Appartamento per le vacanze a Meltina | Hotel zum L\u00f6wen","isPartOf":{"@id":"https:\/\/www.zumloewen.com\/it\/#website"},"datePublished":"2024-09-03T06:42:53+00:00","dateModified":"2024-09-11T11:53:52+00:00","description":"Il nostro accogliente appartamento per le vacanze vi offre la sistemazione perfetta per una vacanza indipendente a Meltina.","breadcrumb":{"@id":"https:\/\/www.zumloewen.com\/it\/camere\/appartamento-per-le-vacanze\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zumloewen.com\/it\/camere\/appartamento-per-le-vacanze\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.zumloewen.com\/it\/camere\/appartamento-per-le-vacanze\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.zumloewen.com\/it\/"},{"@type":"ListItem","position":2,"name":"Appartamento per le vacanze"}]},{"@type":"WebSite","@id":"https:\/\/www.zumloewen.com\/it\/#website","url":"https:\/\/www.zumloewen.com\/it\/","name":"Zum L\u00f6wen M\u00f6lten","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zumloewen.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.zumloewen.com\/it\/wp-json\/wp\/v2\/zimmer\/370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zumloewen.com\/it\/wp-json\/wp\/v2\/zimmer"}],"about":[{"href":"https:\/\/www.zumloewen.com\/it\/wp-json\/wp\/v2\/types\/zimmer"}],"wp:attachment":[{"href":"https:\/\/www.zumloewen.com\/it\/wp-json\/wp\/v2\/media?parent=370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}